{"id":122317,"date":"2022-02-11T11:36:17","date_gmt":"2022-02-11T16:36:17","guid":{"rendered":"https:\/\/www.aecl.ca\/?p=122317"},"modified":"2022-02-11T11:36:17","modified_gmt":"2022-02-11T16:36:17","slug":"amy-gottschling-assumera-le-role-de-vice-presidente-science-technologie-et-surveillance-commerciale-a-eacl","status":"publish","type":"post","link":"https:\/\/www.aecl.ca\/fr\/amy-gottschling-assumera-le-role-de-vice-presidente-science-technologie-et-surveillance-commerciale-a-eacl\/","title":{"rendered":"Amy Gottschling assumera le r\u00f4le de vice-pr\u00e9sidente, Science, technologie et surveillance commerciale \u00e0 EACL"},"content":{"rendered":"<p>\u00c9nergie atomique du Canada limit\u00e9e (EACL) est heureuse d&rsquo;accueillir Amy Gottschling au poste de vice-pr\u00e9sidente, Science, technologie et surveillance commerciale d&rsquo;EACL, \u00e0 compter du 14 f\u00e9vrier 2022.<\/p>\n<p>En tant que vice-pr\u00e9sidente, Surveillance scientifique, technologique et commerciale, Amy sera charg\u00e9e de superviser le rendement des projets et des programmes de science et de technologie nucl\u00e9aires des Laboratoires Nucl\u00e9aires Canadiens pour le gouvernement du Canada, ainsi que des projets de science et de technologie commerciales pour des clients tiers.<\/p>\n<p>Amy a plus de 20 ans d&rsquo;exp\u00e9rience, ayant r\u00e9cemment occup\u00e9 le poste de vice-pr\u00e9sidente des services de chimie et de mat\u00e9riaux radioactifs chez Kinectrics Inc. o\u00f9 elle a g\u00e9r\u00e9 un portefeuille englobant la recherche et le d\u00e9veloppement, le traitement des d\u00e9chets radioactifs et la planification du d\u00e9classement, la radiochimie, les technologies du tritium et les isotopes m\u00e9dicaux.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c9nergie atomique du Canada limit\u00e9e (EACL) est heureuse d&rsquo;accueillir Amy Gottschling au poste de vice-pr\u00e9sidente, Science, technologie et surveillance commerciale d&rsquo;EACL, \u00e0 compter du 14 f\u00e9vrier 2022. En tant que vice-pr\u00e9sidente, Surveillance scientifique, technologique et commerciale, Amy sera charg\u00e9e de superviser le rendement des projets et des programmes de science et de technologie nucl\u00e9aires des [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":122315,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[16],"tags":[],"class_list":["post-122317","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Amy Gottschling assumera le r\u00f4le de vice-pr\u00e9sidente, Science, technologie et surveillance commerciale \u00e0 EACL - EACL<\/title>\n<meta name=\"description\" content=\"\u00c9nergie atomique du Canada limit\u00e9e (EACL) est heureuse d&#039;accueillir Amy Gottschling au poste de vice-pr\u00e9sidente, Science, technologie et surveillance\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.aecl.ca\/fr\/amy-gottschling-assumera-le-role-de-vice-presidente-science-technologie-et-surveillance-commerciale-a-eacl\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Amy Gottschling assumera le r\u00f4le de vice-pr\u00e9sidente, Science, technologie et surveillance commerciale \u00e0 EACL\" \/>\n<meta property=\"og:description\" content=\"\u00c9nergie atomique du Canada limit\u00e9e (EACL) est heureuse d&#039;accueillir Amy Gottschling au poste de vice-pr\u00e9sidente, Science, technologie et surveillance\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.aecl.ca\/fr\/amy-gottschling-assumera-le-role-de-vice-presidente-science-technologie-et-surveillance-commerciale-a-eacl\/\" \/>\n<meta property=\"og:site_name\" content=\"EACL\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-11T16:36:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.aecl.ca\/wp-content\/uploads\/2022\/02\/Amy-Gottschling-2022-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2522\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Maude-\u00c9milie Page\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AECL_EACL\" \/>\n<meta name=\"twitter:site\" content=\"@AECL_EACL\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maude-\u00c9milie Page\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.aecl.ca\\\/fr\\\/amy-gottschling-assumera-le-role-de-vice-presidente-science-technologie-et-surveillance-commerciale-a-eacl\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aecl.ca\\\/fr\\\/amy-gottschling-assumera-le-role-de-vice-presidente-science-technologie-et-surveillance-commerciale-a-eacl\\\/\"},\"author\":{\"name\":\"Maude-\u00c9milie Page\",\"@id\":\"https:\\\/\\\/www.aecl.ca\\\/fr\\\/#\\\/schema\\\/person\\\/40f0e182e778835701c974a17962684d\"},\"headline\":\"Amy Gottschling assumera le r\u00f4le de vice-pr\u00e9sidente, Science, technologie et surveillance commerciale \u00e0 EACL\",\"datePublished\":\"2022-02-11T16:36:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.aecl.ca\\\/fr\\\/amy-gottschling-assumera-le-role-de-vice-presidente-science-technologie-et-surveillance-commerciale-a-eacl\\\/\"},\"wordCount\":164,\"publisher\":{\"@id\":\"https:\\\/\\\/www.aecl.ca\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aecl.ca\\\/fr\\\/amy-gottschling-assumera-le-role-de-vice-presidente-science-technologie-et-surveillance-commerciale-a-eacl\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aecl.ca\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Amy-Gottschling-2022-scaled.jpg\",\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.aecl.ca\\\/fr\\\/amy-gottschling-assumera-le-role-de-vice-presidente-science-technologie-et-surveillance-commerciale-a-eacl\\\/\",\"url\":\"https:\\\/\\\/www.aecl.ca\\\/fr\\\/amy-gottschling-assumera-le-role-de-vice-presidente-science-technologie-et-surveillance-commerciale-a-eacl\\\/\",\"name\":\"Amy Gottschling assumera le r\u00f4le de vice-pr\u00e9sidente, Science, technologie et surveillance commerciale \u00e0 EACL - EACL\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.aecl.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.aecl.ca\\\/fr\\\/amy-gottschling-assumera-le-role-de-vice-presidente-science-technologie-et-surveillance-commerciale-a-eacl\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aecl.ca\\\/fr\\\/amy-gottschling-assumera-le-role-de-vice-presidente-science-technologie-et-surveillance-commerciale-a-eacl\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.aecl.ca\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Amy-Gottschling-2022-scaled.jpg\",\"datePublished\":\"2022-02-11T16:36:17+00:00\",\"description\":\"\u00c9nergie atomique du Canada limit\u00e9e (EACL) est heureuse d'accueillir Amy Gottschling au poste de vice-pr\u00e9sidente, Science, technologie et surveillance\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.aecl.ca\\\/fr\\\/amy-gottschling-assumera-le-role-de-vice-presidente-science-technologie-et-surveillance-commerciale-a-eacl\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.aecl.ca\\\/fr\\\/amy-gottschling-assumera-le-role-de-vice-presidente-science-technologie-et-surveillance-commerciale-a-eacl\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.aecl.ca\\\/fr\\\/amy-gottschling-assumera-le-role-de-vice-presidente-science-technologie-et-surveillance-commerciale-a-eacl\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.aecl.ca\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Amy-Gottschling-2022-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.aecl.ca\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Amy-Gottschling-2022-scaled.jpg\",\"width\":2560,\"height\":2522},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.aecl.ca\\\/fr\\\/amy-gottschling-assumera-le-role-de-vice-presidente-science-technologie-et-surveillance-commerciale-a-eacl\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.aecl.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Amy Gottschling assumera le r\u00f4le de vice-pr\u00e9sidente, Science, technologie et surveillance commerciale \u00e0 EACL\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.aecl.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.aecl.ca\\\/fr\\\/\",\"name\":\"EACL\",\"description\":\"\u00c9nergie atomique du Canada limit\u00e9e\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.aecl.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.aecl.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.aecl.ca\\\/fr\\\/#organization\",\"name\":\"Atomic Energy Canada Limited AECL\",\"url\":\"https:\\\/\\\/www.aecl.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.aecl.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.aecl.ca\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/AECL-Stacked-Blue.png\",\"contentUrl\":\"https:\\\/\\\/www.aecl.ca\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/AECL-Stacked-Blue.png\",\"width\":1600,\"height\":560,\"caption\":\"Atomic Energy Canada Limited AECL\"},\"image\":{\"@id\":\"https:\\\/\\\/www.aecl.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/AECL_EACL\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/aecl\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.aecl.ca\\\/fr\\\/#\\\/schema\\\/person\\\/40f0e182e778835701c974a17962684d\",\"name\":\"Maude-\u00c9milie Page\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cf6204018339b5db62abe1d62f793fba1c3c37dbe40e2af514390dea80b3c4fc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cf6204018339b5db62abe1d62f793fba1c3c37dbe40e2af514390dea80b3c4fc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cf6204018339b5db62abe1d62f793fba1c3c37dbe40e2af514390dea80b3c4fc?s=96&d=mm&r=g\",\"caption\":\"Maude-\u00c9milie Page\"},\"sameAs\":[\"excentric-admin\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Amy Gottschling assumera le r\u00f4le de vice-pr\u00e9sidente, Science, technologie et surveillance commerciale \u00e0 EACL - EACL","description":"\u00c9nergie atomique du Canada limit\u00e9e (EACL) est heureuse d'accueillir Amy Gottschling au poste de vice-pr\u00e9sidente, Science, technologie et surveillance","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.aecl.ca\/fr\/amy-gottschling-assumera-le-role-de-vice-presidente-science-technologie-et-surveillance-commerciale-a-eacl\/","og_locale":"fr_FR","og_type":"article","og_title":"Amy Gottschling assumera le r\u00f4le de vice-pr\u00e9sidente, Science, technologie et surveillance commerciale \u00e0 EACL","og_description":"\u00c9nergie atomique du Canada limit\u00e9e (EACL) est heureuse d'accueillir Amy Gottschling au poste de vice-pr\u00e9sidente, Science, technologie et surveillance","og_url":"https:\/\/www.aecl.ca\/fr\/amy-gottschling-assumera-le-role-de-vice-presidente-science-technologie-et-surveillance-commerciale-a-eacl\/","og_site_name":"EACL","article_published_time":"2022-02-11T16:36:17+00:00","og_image":[{"width":2560,"height":2522,"url":"https:\/\/www.aecl.ca\/wp-content\/uploads\/2022\/02\/Amy-Gottschling-2022-scaled.jpg","type":"image\/jpeg"}],"author":"Maude-\u00c9milie Page","twitter_card":"summary_large_image","twitter_creator":"@AECL_EACL","twitter_site":"@AECL_EACL","twitter_misc":{"\u00c9crit par":"Maude-\u00c9milie Page","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.aecl.ca\/fr\/amy-gottschling-assumera-le-role-de-vice-presidente-science-technologie-et-surveillance-commerciale-a-eacl\/#article","isPartOf":{"@id":"https:\/\/www.aecl.ca\/fr\/amy-gottschling-assumera-le-role-de-vice-presidente-science-technologie-et-surveillance-commerciale-a-eacl\/"},"author":{"name":"Maude-\u00c9milie Page","@id":"https:\/\/www.aecl.ca\/fr\/#\/schema\/person\/40f0e182e778835701c974a17962684d"},"headline":"Amy Gottschling assumera le r\u00f4le de vice-pr\u00e9sidente, Science, technologie et surveillance commerciale \u00e0 EACL","datePublished":"2022-02-11T16:36:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.aecl.ca\/fr\/amy-gottschling-assumera-le-role-de-vice-presidente-science-technologie-et-surveillance-commerciale-a-eacl\/"},"wordCount":164,"publisher":{"@id":"https:\/\/www.aecl.ca\/fr\/#organization"},"image":{"@id":"https:\/\/www.aecl.ca\/fr\/amy-gottschling-assumera-le-role-de-vice-presidente-science-technologie-et-surveillance-commerciale-a-eacl\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aecl.ca\/wp-content\/uploads\/2022\/02\/Amy-Gottschling-2022-scaled.jpg","articleSection":["Non classifi\u00e9(e)"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.aecl.ca\/fr\/amy-gottschling-assumera-le-role-de-vice-presidente-science-technologie-et-surveillance-commerciale-a-eacl\/","url":"https:\/\/www.aecl.ca\/fr\/amy-gottschling-assumera-le-role-de-vice-presidente-science-technologie-et-surveillance-commerciale-a-eacl\/","name":"Amy Gottschling assumera le r\u00f4le de vice-pr\u00e9sidente, Science, technologie et surveillance commerciale \u00e0 EACL - EACL","isPartOf":{"@id":"https:\/\/www.aecl.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.aecl.ca\/fr\/amy-gottschling-assumera-le-role-de-vice-presidente-science-technologie-et-surveillance-commerciale-a-eacl\/#primaryimage"},"image":{"@id":"https:\/\/www.aecl.ca\/fr\/amy-gottschling-assumera-le-role-de-vice-presidente-science-technologie-et-surveillance-commerciale-a-eacl\/#primaryimage"},"thumbnailUrl":"https:\/\/www.aecl.ca\/wp-content\/uploads\/2022\/02\/Amy-Gottschling-2022-scaled.jpg","datePublished":"2022-02-11T16:36:17+00:00","description":"\u00c9nergie atomique du Canada limit\u00e9e (EACL) est heureuse d'accueillir Amy Gottschling au poste de vice-pr\u00e9sidente, Science, technologie et surveillance","breadcrumb":{"@id":"https:\/\/www.aecl.ca\/fr\/amy-gottschling-assumera-le-role-de-vice-presidente-science-technologie-et-surveillance-commerciale-a-eacl\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.aecl.ca\/fr\/amy-gottschling-assumera-le-role-de-vice-presidente-science-technologie-et-surveillance-commerciale-a-eacl\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.aecl.ca\/fr\/amy-gottschling-assumera-le-role-de-vice-presidente-science-technologie-et-surveillance-commerciale-a-eacl\/#primaryimage","url":"https:\/\/www.aecl.ca\/wp-content\/uploads\/2022\/02\/Amy-Gottschling-2022-scaled.jpg","contentUrl":"https:\/\/www.aecl.ca\/wp-content\/uploads\/2022\/02\/Amy-Gottschling-2022-scaled.jpg","width":2560,"height":2522},{"@type":"BreadcrumbList","@id":"https:\/\/www.aecl.ca\/fr\/amy-gottschling-assumera-le-role-de-vice-presidente-science-technologie-et-surveillance-commerciale-a-eacl\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.aecl.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Amy Gottschling assumera le r\u00f4le de vice-pr\u00e9sidente, Science, technologie et surveillance commerciale \u00e0 EACL"}]},{"@type":"WebSite","@id":"https:\/\/www.aecl.ca\/fr\/#website","url":"https:\/\/www.aecl.ca\/fr\/","name":"EACL","description":"\u00c9nergie atomique du Canada limit\u00e9e","publisher":{"@id":"https:\/\/www.aecl.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.aecl.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.aecl.ca\/fr\/#organization","name":"Atomic Energy Canada Limited AECL","url":"https:\/\/www.aecl.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.aecl.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.aecl.ca\/wp-content\/uploads\/2019\/01\/AECL-Stacked-Blue.png","contentUrl":"https:\/\/www.aecl.ca\/wp-content\/uploads\/2019\/01\/AECL-Stacked-Blue.png","width":1600,"height":560,"caption":"Atomic Energy Canada Limited AECL"},"image":{"@id":"https:\/\/www.aecl.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/AECL_EACL","https:\/\/www.linkedin.com\/company\/aecl"]},{"@type":"Person","@id":"https:\/\/www.aecl.ca\/fr\/#\/schema\/person\/40f0e182e778835701c974a17962684d","name":"Maude-\u00c9milie Page","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/cf6204018339b5db62abe1d62f793fba1c3c37dbe40e2af514390dea80b3c4fc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cf6204018339b5db62abe1d62f793fba1c3c37dbe40e2af514390dea80b3c4fc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cf6204018339b5db62abe1d62f793fba1c3c37dbe40e2af514390dea80b3c4fc?s=96&d=mm&r=g","caption":"Maude-\u00c9milie Page"},"sameAs":["excentric-admin"]}]}},"_links":{"self":[{"href":"https:\/\/www.aecl.ca\/fr\/wp-json\/wp\/v2\/posts\/122317","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aecl.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aecl.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aecl.ca\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aecl.ca\/fr\/wp-json\/wp\/v2\/comments?post=122317"}],"version-history":[{"count":0,"href":"https:\/\/www.aecl.ca\/fr\/wp-json\/wp\/v2\/posts\/122317\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aecl.ca\/fr\/wp-json\/wp\/v2\/media\/122315"}],"wp:attachment":[{"href":"https:\/\/www.aecl.ca\/fr\/wp-json\/wp\/v2\/media?parent=122317"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aecl.ca\/fr\/wp-json\/wp\/v2\/categories?post=122317"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aecl.ca\/fr\/wp-json\/wp\/v2\/tags?post=122317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}